{"id":38057,"date":"2026-03-10T14:58:28","date_gmt":"2026-03-10T07:58:28","guid":{"rendered":"https:\/\/www.biotec.or.th\/home\/?p=38057"},"modified":"2026-03-10T15:06:59","modified_gmt":"2026-03-10T08:06:59","slug":"biotec-nstda-asf-vaccine-field-test-collaboration-dld","status":"publish","type":"post","link":"https:\/\/www.biotec.or.th\/home\/biotec-nstda-asf-vaccine-field-test-collaboration-dld\/","title":{"rendered":"\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 ASF \u0e43\u0e19\u0e2a\u0e38\u0e01\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"38057\" class=\"elementor elementor-38057\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a183bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a183bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15f31f8\" data-id=\"15f31f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e809bb elementor-widget elementor-widget-image\" data-id=\"2e809bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"660\" src=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1-1024x660.jpg\" class=\"attachment-large size-large wp-image-38059\" alt=\"\" srcset=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1-1024x660.jpg 1024w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1-300x193.jpg 300w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1-768x495.jpg 768w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1-1536x989.jpg 1536w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1-440x283.jpg 440w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a57acb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a57acb1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-267c061\" data-id=\"267c061\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dde6cc8 elementor-widget elementor-widget-text-editor\" data-id=\"dde6cc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e23\u0e38\u0e13 \u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u00a0 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e &#8211; <strong>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e40\u0e0a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c \u0e2d\u0e23\u0e23\u0e16\u0e25\u0e31\u0e07\u0e23\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e14\u0e23.\u0e2d\u0e19\u0e31\u0e15\u0e19\u0e4c \u0e08\u0e07\u0e41\u0e01\u0e49\u0e27\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c (\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c) \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e27\u0e34\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e40\u0e02\u0e49\u0e32\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e2d\u0e2b\u0e34\u0e27\u0e32\u0e15\u0e4c\u0e41\u0e2d\u0e1f\u0e23\u0e34\u0e01\u0e32\u0e43\u0e19\u0e2a\u0e38\u0e01\u0e23 (<\/strong><strong>African Swine Fever: ASF) \u0e41\u0e01\u0e48\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed03724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed03724\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a0a5bf\" data-id=\"5a0a5bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1756ae8 elementor-widget elementor-widget-image\" data-id=\"1756ae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-1024x768.jpg\" class=\"attachment-large size-large wp-image-38060\" alt=\"\" srcset=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-1024x768.jpg 1024w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-300x225.jpg 300w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-768x576.jpg 768w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-1536x1152.jpg 1536w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-440x330.jpg 440w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2-600x450.jpg 600w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-2.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ef06b3d\" data-id=\"ef06b3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7213a30 elementor-widget elementor-widget-image\" data-id=\"7213a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-1024x768.jpg\" class=\"attachment-large size-large wp-image-38061\" alt=\"\" srcset=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-1024x768.jpg 1024w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-300x225.jpg 300w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-768x576.jpg 768w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-1536x1152.jpg 1536w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-440x330.jpg 440w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3-600x450.jpg 600w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-3.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-151c33a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"151c33a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52e4d0e\" data-id=\"52e4d0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c72575c elementor-widget elementor-widget-text-editor\" data-id=\"c72575c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 ASF \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e2d\u0e2b\u0e34\u0e27\u0e32\u0e15\u0e4c\u0e41\u0e2d\u0e1f\u0e23\u0e34\u0e01\u0e32\u0e43\u0e19\u0e2a\u0e38\u0e01\u0e23 (African Swine Fever: ASF) \u0e08\u0e32\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01\u0e14\u0e49\u0e32\u0e19\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e2d\u0e13\u0e39\u0e0a\u0e35\u0e27\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e38\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e24\u0e17\u0e18\u0e34\u0e4c (Live Attenuated Vaccine: LAV) \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e08\u0e32\u0e01\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2a\u0e39\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e20\u0e39\u0e21\u0e34\u0e04\u0e38\u0e49\u0e21\u0e01\u0e31\u0e19\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a ASF \u0e41\u0e25\u0e30\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b82135c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b82135c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adc5bfc\" data-id=\"adc5bfc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe170fa elementor-widget elementor-widget-image\" data-id=\"fe170fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4-1024x768.jpg\" class=\"attachment-large size-large wp-image-38062\" alt=\"\" srcset=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4-1024x768.jpg 1024w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4-300x225.jpg 300w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4-768x576.jpg 768w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4-440x330.jpg 440w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4-600x450.jpg 600w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-4.jpg 1312w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fd6ef43\" data-id=\"fd6ef43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9c6ae7 elementor-widget elementor-widget-image\" data-id=\"e9c6ae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-1024x768.jpg\" class=\"attachment-large size-large wp-image-38063\" alt=\"\" srcset=\"https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-1024x768.jpg 1024w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-300x225.jpg 300w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-768x576.jpg 768w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-1536x1152.jpg 1536w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-440x330.jpg 440w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5-600x450.jpg 600w, https:\/\/biotec.or.th\/home\/wp-content\/uploads\/2026\/03\/biotec-nstda-asf-vaccine-field-test-collaboration-dld-5.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5032c0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5032c0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7221442\" data-id=\"7221442\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a37d8f5 elementor-widget elementor-widget-text-editor\" data-id=\"a37d8f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e20\u0e32\u0e04\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e08\u0e32\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e20\u0e32\u0e04\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e44\u0e01\u0e2b\u0e25\u0e31\u0e01\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/span><\/p><p><span style=\"color: #000000;\">\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e44\u0e17\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1e\u0e23\u0e30\u0e1e\u0e34\u0e23\u0e38\u0e13 \u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u00a0 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e &#8211; \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e40\u0e0a\u0e32\u0e27\u0e23\u0e35\u0e22\u0e4c \u0e2d\u0e23\u0e23\u0e16\u0e25\u0e31\u0e07\u0e23\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e14\u0e23.\u0e2d\u0e19\u0e31\u0e15\u0e19\u0e4c \u0e08\u0e07\u0e41\u0e01\u0e49\u0e27\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c (\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c) \u0e2a\u0e27\u0e17\u0e0a. \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e27\u0e34\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e40\u0e02\u0e49\u0e32\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e2d\u0e2b\u0e34\u0e27\u0e32\u0e15\u0e4c\u0e41\u0e2d\u0e1f\u0e23\u0e34\u0e01\u0e32\u0e43\u0e19\u0e2a\u0e38\u0e01\u0e23 (African Swine Fever: ASF) \u0e41\u0e01\u0e48\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 ASF \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e2a\u0e27\u0e17\u0e0a. \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e2d\u0e2b\u0e34\u0e27\u0e32\u0e15\u0e4c\u0e41\u0e2d\u0e1f\u0e23\u0e34\u0e01\u0e32\u0e43\u0e19\u0e2a\u0e38\u0e01\u0e23 (African Swine Fever: ASF) [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":38058,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1],"tags":[264,318,3161,2534,3159],"class_list":["post-38057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-public","tag-biotec-th","tag-nstda","tag-3161","tag-asf","tag-3159"],"_links":{"self":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts\/38057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/comments?post=38057"}],"version-history":[{"count":11,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts\/38057\/revisions"}],"predecessor-version":[{"id":38075,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts\/38057\/revisions\/38075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/media\/38058"}],"wp:attachment":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/media?parent=38057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/categories?post=38057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/tags?post=38057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}