{"id":7424,"date":"2020-05-08T09:20:26","date_gmt":"2020-05-08T02:20:26","guid":{"rendered":"https:\/\/www.biotec.or.th\/home\/?p=7424"},"modified":"2020-05-08T09:20:28","modified_gmt":"2020-05-08T02:20:28","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2-6","status":"publish","type":"post","link":"https:\/\/www.biotec.or.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2-6\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1c\u0e39\u0e49\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e15\u0e32\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e2a.05\/58 \u0e25\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2557"},"content":{"rendered":"\n<p>\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e28\u0e0a.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a Cooling Pad \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 Chiller \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 Pre-Cooling \u0e42\u0e14\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e59 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e57 \u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e52 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e58 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e50\u0e58.\u0e53\u0e50 \u0e19. \u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e51\u0e56.\u0e53\u0e50 \u0e19. \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e52 \u0e23\u0e32\u0e22\u0e19\u0e31\u0e49\u0e19<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2f \u0e44\u0e14\u0e49\u0e15\u0e23\u0e27\u0e08\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e36\u0e07\u0e02\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e33\u0e19\u0e27\u0e19 \u0e52 \u0e23\u0e32\u0e22 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p>\u0e51. \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e22\u0e39\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e22\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14<br>\u0e52. \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e21\u0e47\u0e04\u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e22\u0e35 \u0e2d\u0e35\u0e42\u0e27\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14<\/p>\n\n\n\n<p><br>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e13 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e53 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e58<\/p>\n\n\n\n<p><br>(\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e2d\u0e19\u0e38\u0e27\u0e31\u0e22\u0e22\u0e32)<br>\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e0b\u0e2d\u0e07\u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e04\u0e32<\/p>\n\n\n\n<p>\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e44\u0e14\u0e49<a href=\"http:\/\/www.biotec.or.th\/th\/images\/procuremant\/2015\/Sobraka%20S.05-58.pdf\"><strong>\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e28\u0e0a.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2a\u0e27\u0e17\u0e0a.) \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2a\u0e2d\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a Cooling Pad \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 Chiller \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 Pre-Cooling \u0e42\u0e14\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e59 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e57 \u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e52\u0e52 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e58 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e50\u0e58.\u0e53\u0e50 \u0e19. \u0e16\u0e36\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e51\u0e56.\u0e53\u0e50 \u0e19. \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e52 \u0e23\u0e32\u0e22\u0e19\u0e31\u0e49\u0e19 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2f \u0e44\u0e14\u0e49\u0e15\u0e23\u0e27\u0e08\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e36\u0e07\u0e02\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e33\u0e19\u0e27\u0e19 \u0e52 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[20],"tags":[],"class_list":["post-7424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-procurement"],"_links":{"self":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts\/7424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/comments?post=7424"}],"version-history":[{"count":0,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/posts\/7424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/media\/7306"}],"wp:attachment":[{"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/media?parent=7424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/categories?post=7424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biotec.or.th\/home\/wp-json\/wp\/v2\/tags?post=7424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}